{"id":613,"date":"2023-10-05T19:19:49","date_gmt":"2023-10-05T19:19:49","guid":{"rendered":"https:\/\/dbsaa.de\/?page_id=613"},"modified":"2024-12-06T07:30:17","modified_gmt":"2024-12-06T07:30:17","slug":"kindergarten","status":"publish","type":"page","link":"https:\/\/dbsaa.de\/de\/kindergarten\/","title":{"rendered":"Kindergarten"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"613\" class=\"elementor elementor-613\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62289c5f elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"62289c5f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6dee6886\" data-id=\"6dee6886\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-11af08fb elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"11af08fb\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d929308\" data-id=\"d929308\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6db1c2e1 elementor-widget elementor-widget-elementskit-heading\" data-id=\"6db1c2e1\" data-element_type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title\">Kindergarten<\/h2><div class=\"ekit_heading_separetor_wraper ekit_heading_elementskit-border-divider\"><div class=\"elementskit-border-divider\"><\/div><\/div>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p><span style=\"font-weight: 400\">In unserem Kindergarten sind etwa 105 Kinder im Alter von 1-6 Jahren eingeschrieben. Die Kinder sind in Gruppen von 16-20 Sch\u00fclern untergebracht, die von deutschsprachigen Erzieherinnen und Erziehern und \u00e4thiopischen Hilfskr\u00e4ften betreut werden.<\/span><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-31d8b3e6\" data-id=\"31d8b3e6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6a232d0b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"6a232d0b\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:&quot;yes&quot;,&quot;_ha_eqh_widget&quot;:[&quot;ha-infobox&quot;],&quot;_ha_eqh_to&quot;:&quot;widget&quot;,&quot;_ha_eqh_disable_on_tablet&quot;:&quot;no&quot;,&quot;_ha_eqh_disable_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5696cd65\" data-id=\"5696cd65\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ebd46d2 ha-infobox-media-dir-top elementor-widget elementor-widget-ha-infobox happy-addon ha-infobox\" data-id=\"1ebd46d2\" data-element_type=\"widget\" data-widget_type=\"ha-infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t\t\t<figure class=\"ha-infobox-figure ha-infobox-figure--image\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"62\" height=\"62\" src=\"https:\/\/dbsaa.de\/wp-content\/uploads\/2023\/10\/Group-35.png\" class=\"elementor-animation-disable-animation attachment-full size-full wp-image-3746\" alt=\"\" \/>\t\t\t<\/figure>\n\t\t\n\t\t<div class=\"ha-infobox-body\">\n\t\t\t<h2 class=\"ha-infobox-title\">P\u00e4dagogischer Ansatz<\/h2>\n\t\t\t\t\t\t\t<div class=\"ha-infobox-text\">\n\t\t\t\t\t<p>Unser p\u00e4dagogischer Ansatz konzentriert sich darauf, die Entwicklungsbed\u00fcrfnisse, Erfahrungen und Interessen jedes einzelnen Kindes zu unterst\u00fctzen. Wir wollen Unabh\u00e4ngigkeit, Einf\u00fchlungsverm\u00f6gen, Frustrationstoleranz und Lernen durch praktisches Spielen und Erkunden f\u00f6rdern. Zu unseren Zielen geh\u00f6rt die F\u00f6rderung der Entwicklung in allen Bereichen, einschlie\u00dflich der k\u00f6rperlichen, kognitiven, sprachlichen, sozial-emotionalen Entwicklung. Dabei ber\u00fccksichtigen wir die Familien- und Lebenssituation des Kindes. <\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3fd05231\" data-id=\"3fd05231\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26d71543 ha-infobox-media-dir-top elementor-widget elementor-widget-ha-infobox happy-addon ha-infobox\" data-id=\"26d71543\" data-element_type=\"widget\" data-widget_type=\"ha-infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t\t\t<figure class=\"ha-infobox-figure ha-infobox-figure--image\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"62\" height=\"62\" src=\"https:\/\/dbsaa.de\/wp-content\/uploads\/2023\/10\/Group-36.png\" class=\"elementor-animation-disable-animation attachment-full size-full wp-image-3747\" alt=\"\" \/>\t\t\t<\/figure>\n\t\t\n\t\t<div class=\"ha-infobox-body\">\n\t\t\t<h2 class=\"ha-infobox-title\">Das Bild vom Kind<\/h2>\n\t\t\t\t\t\t\t<div class=\"ha-infobox-text\">\n\t\t\t\t\t<p>Wir sehen jedes Kind als etwas Besonderes und Einzigartiges mit seinen eigenen St\u00e4rken, Talenten, Interessen, Bed\u00fcrfnissen und Lernstilen. Unsere Aufgabe ist es, die Individualit\u00e4t und das Selbstvertrauen eines jeden Kindes zu f\u00f6rdern und zu st\u00e4rken. Wir wollen ihr positives Selbstbild unterst\u00fctzen und ihnen helfen, ihre F\u00e4higkeiten und ihr Potenzial als Individuen auszubauen.<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2ef292f2\" data-id=\"2ef292f2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1e21c5d1 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"1e21c5d1\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-37d7f673\" data-id=\"37d7f673\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4ffa6013 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no elementor-invisible\" data-id=\"4ffa6013\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-23e48948\" data-id=\"23e48948\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b3b2078 elementor-widget elementor-widget-elementskit-heading\" data-id=\"1b3b2078\" data-element_type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title\">Einrichtung und Tagesablauf<\/h2><div class=\"ekit_heading_separetor_wraper ekit_heading_elementskit-border-divider\"><div class=\"elementskit-border-divider\"><\/div><\/div>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p><span style=\"font-weight: 400\">Unsere Einrichtung verf\u00fcgt \u00fcber mehrere R\u00e4ume, darunter einen gro\u00dfen Krippenraum, drei Kindergartengruppenr\u00e4ume, zwei Vorschulr\u00e4ume, ein Au\u00dfengel\u00e4nde und mehr.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Der Tagesplan sorgt f\u00fcr Struktur und Routine. Er beinhaltet Zeit f\u00fcr Spiel, Lernaktivit\u00e4ten, Mahlzeiten, Ruhezeiten und gezielte Sprachf\u00f6rderung. H\u00f6hepunkte des Tagesablaufs:<\/span><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-56daff97\" data-id=\"56daff97\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8a93c1 elementor-widget elementor-widget-elementskit-heading\" data-id=\"a8a93c1\" data-element_type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title\">Vormittag<\/h2><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb0cba1 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"fb0cba1\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text-left icon-lef-right-aligin elementor-animation- media\">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  text-center\">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon fas fa-bus-alt\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    7:30 Uhr - Ankunft der Kinder                <\/h3>\n                                            <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-706c0211 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"706c0211\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text-left icon-lef-right-aligin elementor-animation- media\">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  text-center\">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon fas fa-utensils\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    8:15 Uhr - Fr\u00fchst\u00fcck                <\/h3>\n                                            <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d55bf16 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"7d55bf16\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text-left icon-lef-right-aligin elementor-animation- media\">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  text-center\">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon fas fa-users\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    8:45 Uhr - Morgenkreis                <\/h3>\n                                            <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a8286d7 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"3a8286d7\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text-left icon-lef-right-aligin elementor-animation- media\">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  text-center\">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon hm hm-group\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    9:15 Uhr - Offene Gruppenarbeit                <\/h3>\n                        \t\t  <p>Sprachf\u00f6rderung, musikalische Fr\u00fcherziehung, Kochen und Backen, Sport...\n<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e5ae537 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"3e5ae537\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text-left icon-lef-right-aligin elementor-animation- media\">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  text-center\">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon fas fa-apple-alt\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    10:45 Uhr - Obstsnack                <\/h3>\n                                            <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57a607c3 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"57a607c3\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text-left icon-lef-right-aligin elementor-animation- media\">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  text-center\">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon icon icon-planet-earth\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    11:00 Uhr - Freies Spiel und Aktivit\u00e4ten im Freien                <\/h3>\n                                            <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5354dce8 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"5354dce8\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text-left icon-lef-right-aligin elementor-animation- media\">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  text-center\">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon fas fa-utensils\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    12:00 Uhr - Mittagessen                <\/h3>\n                                            <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79b2207a ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"79b2207a\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text-left icon-lef-right-aligin elementor-animation- media\">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  text-center\">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon fas fa-bed\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    13:00 Uhr - Mittagsschlaf\/Ruhezeit                <\/h3>\n                                            <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-21178b12\" data-id=\"21178b12\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e8a90a elementor-widget elementor-widget-elementskit-heading\" data-id=\"8e8a90a\" data-element_type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title\">Nachmittag<\/h2><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b75a6f1 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"6b75a6f1\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text-left icon-lef-right-aligin elementor-animation- media\">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  text-center\">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon fas fa-users\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    14:00 Uhr - Nachmittagssnack                <\/h3>\n                                            <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e514d3c ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"e514d3c\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text-left icon-lef-right-aligin elementor-animation- media\">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  text-center\">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon fas fa-language\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    14:15 Uhr - Sprachf\u00f6rderung und Durchf\u00fchrung gemeinsamer Projektarbeit zu aktuellen Themen (Weihnachten, Ostern, Meskel etc.)                <\/h3>\n                                            <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f7d587d ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"3f7d587d\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text-left icon-lef-right-aligin elementor-animation- media\">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  text-center\">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon fas fa-running\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    15:00 Uhr - Freies Spiel\/Sport im Garten                <\/h3>\n                                            <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61c2785a ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"61c2785a\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text-left icon-lef-right-aligin elementor-animation- media\">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  text-center\">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon fas fa-bus-alt\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    16:00 Uhr - Abholzeit                <\/h3>\n                                            <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-2802d2a elementor-widget elementor-widget-spacer\" data-id=\"2802d2a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.17.0 - 08-11-2023 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container{height:100%;width:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty,.e-con>.elementor-widget-spacer.elementor-widget-empty{position:relative;min-height:22px;min-width:22px}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon,.e-con>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon{position:absolute;top:0;bottom:0;left:0;right:0;margin:auto;padding:0;width:22px;height:22px}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-46678f6 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"46678f6\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-821caad e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"821caad\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0321ced elementor-widget elementor-widget-elementskit-heading\" data-id=\"0321ced\" data-element_type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title\">Angebote und Aktivit\u00e4ten<\/h2>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p><span style=\"font-weight: 400\">Unsere p\u00e4dagogischen Konzepte orientieren sich eng am Th\u00fcringer Rahmenlehrplan und konzentrieren sich auf zentrale Lernbereiche, die die kindliche Entwicklung f\u00f6rdern. Zu diesen Bereichen geh\u00f6ren: Sprachentwicklung, mathematisches Denken, musikalische Bildung, k\u00fcnstlerische und \u00e4sthetische Entwicklung, naturwissenschaftliche Bildung, Entwicklung von motorischen und gesundheitlichen F\u00e4higkeiten sowie soziokulturelle\/moralische\/religi\u00f6se Bildung.\nWir haben ein solides Sprachlern- und F\u00f6rderprogramm namens KonLab. Dieses forschungsbasierte Programm wurde f\u00fcr die fr\u00fche Sprachentwicklung entwickelt und ist f\u00fcr Kinder mit Sprachverz\u00f6gerungen, mit Migrationshintergrund oder f\u00fcr Kinder, die Deutsch im Ausland lernen, von Vorteil. Die Kinder erhalten t\u00e4glich 1-2 Stunden gezielten KonLab-Unterricht, um ihre kommunikativen und sprachlichen F\u00e4higkeiten zu f\u00f6rdern<\/span><\/p>\n<p><span style=\"font-weight: 400\">Unsere typischen t\u00e4glichen Aktivit\u00e4ten bieten eine ausgewogene Mischung aus Struktur und freier Erkundung. Dazu geh\u00f6ren der Morgenkreis, Kreativstunden, Musik und Rollenspiele. Sport und motorische Aktivit\u00e4ten f\u00f6rdern die k\u00f6rperliche Koordination und die Gesundheit. Freies Spiel ist ebenfalls wichtig, da die Kinder die Aktivit\u00e4ten nach ihren eigenen Interessen ausw\u00e4hlen und sozial interagieren.<\/span><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-60c06b4 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"60c06b4\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-392c039 elementor-widget elementor-widget-image\" data-id=\"392c039\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.17.0 - 08-11-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"770\" height=\"514\" src=\"https:\/\/dbsaa.de\/wp-content\/uploads\/2024\/02\/IMG_0790-1024x683.jpg\" class=\"attachment-large size-large wp-image-6350\" alt=\"\" srcset=\"https:\/\/dbsaa.de\/wp-content\/uploads\/2024\/02\/IMG_0790-1024x683.jpg 1024w, https:\/\/dbsaa.de\/wp-content\/uploads\/2024\/02\/IMG_0790-300x200.jpg 300w, https:\/\/dbsaa.de\/wp-content\/uploads\/2024\/02\/IMG_0790-768x512.jpg 768w, https:\/\/dbsaa.de\/wp-content\/uploads\/2024\/02\/IMG_0790-1536x1024.jpg 1536w, https:\/\/dbsaa.de\/wp-content\/uploads\/2024\/02\/IMG_0790-2048x1365.jpg 2048w, https:\/\/dbsaa.de\/wp-content\/uploads\/2024\/02\/IMG_0790-18x12.jpg 18w, https:\/\/dbsaa.de\/wp-content\/uploads\/2024\/02\/IMG_0790-600x400.jpg 600w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-46467726 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"46467726\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3447a844\" data-id=\"3447a844\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-51563a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"51563a2\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b3a7d94\" data-id=\"b3a7d94\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e5da07 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"4e5da07\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text-left icon-lef-right-aligin elementor-animation- media\">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  text-center\">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon fab fa-odnoklassniki\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Krippengruppe                <\/h3>\n                        \t\t  <p>Unsere Kinderkrippe bietet spezielle Betreuung und Erziehung f\u00fcr S\u00e4uglinge und Kleinkinder. Mit einem geringeren Betreuungsschl\u00fcssel k\u00f6nnen wir unseren kleinsten Sch\u00fctzlingen eine individuelle Betreuung bieten. Die Kinderkrippe konzentriert sich auf sensorisches Lernen, motorische F\u00e4higkeiten, Kommunikationsbed\u00fcrfnisse und Sozialisierung.\nDiese alters\u00fcbergreifende Gruppenzusammensetzung erm\u00f6glicht es den Kindern, gemeinsam zu lernen und gleichzeitig auf ihrem eigenen Entwicklungsniveau unterrichtet zu werden.\n<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e20584a elementor-widget__width-initial elementor-widget elementor-widget-elementskit-heading\" data-id=\"e20584a\" data-element_type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--subtitle elementskit-section-subtitle  elementskit-style-border\">\n\t\t\t\t\t\tM\u00e4uschengruppe\n\t\t\t\t\t<\/h2><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4009c16\" data-id=\"4009c16\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5aea2577 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"5aea2577\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text-left icon-lef-right-aligin elementor-animation- media\">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  text-center\">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon icon icon-school\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Kindergarten                <\/h3>\n                        \t\t  <p>Die Kindergartengruppen umfassen jeweils 16-20 Kinder. Die Kinder bleiben in der gleichen Gruppe mit Gleichaltrigen und Erzieherinnen und Erziehern, um eine gewisse Kontinuit\u00e4t zu gew\u00e4hrleisten. Die Gruppen sind nach Tieren benannt, um den Kindern mehr Spa\u00df zu bieten und sie zu motivieren.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6f0084 elementor-widget__width-initial elementor-widget elementor-widget-elementskit-heading\" data-id=\"a6f0084\" data-element_type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--subtitle elementskit-section-subtitle  elementskit-style-border\">\n\t\t\t\t\t\tZebragruppe\n\t\t\t\t\t<\/h2><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7e6d8e elementor-widget__width-initial elementor-widget elementor-widget-elementskit-heading\" data-id=\"e7e6d8e\" data-element_type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--subtitle elementskit-section-subtitle  elementskit-style-border\">\n\t\t\t\t\t\tElefantengruppe\n\t\t\t\t\t<\/h2><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15bb66a elementor-widget__width-initial elementor-widget elementor-widget-elementskit-heading\" data-id=\"15bb66a\" data-element_type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--subtitle elementskit-section-subtitle  elementskit-style-border\">\n\t\t\t\t\t\tKamelgruppe\n\t\t\t\t\t<\/h2><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b6bc539 elementor-hidden-tablet\" data-id=\"b6bc539\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e9c64b ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"0e9c64b\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text-left icon-lef-right-aligin elementor-animation- media\">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  text-center\">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon fas fa-laptop\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Vorschulgruppen                <\/h3>\n                        \t\t  <p>Die Vorschulgruppen erleichtern den Kindern den \u00dcbergang zum Lernen in der Grundschule. Der Lehrplan konzentriert sich mehr auf fr\u00fche Mathematik, Lese- und Schreibf\u00e4higkeiten und sozial-emotionale F\u00e4higkeiten, um sie auf die erste Klasse vorzubereiten.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e354475 elementor-widget__width-initial elementor-widget elementor-widget-elementskit-heading\" data-id=\"e354475\" data-element_type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--subtitle elementskit-section-subtitle  elementskit-style-border\">\n\t\t\t\t\t\tLeopardengruppe\n\t\t\t\t\t<\/h2><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1da7bde elementor-widget__width-initial elementor-widget elementor-widget-elementskit-heading\" data-id=\"1da7bde\" data-element_type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--subtitle elementskit-section-subtitle  elementskit-style-border\">\n\t\t\t\t\t\tGiraffengruppe\n\t\t\t\t\t<\/h2><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-b296979 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"b296979\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-aa85c2a e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"aa85c2a\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9ed3cf1 elementor-widget elementor-widget-elementskit-heading\" data-id=\"9ed3cf1\" data-element_type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title\"> Zusammenarbeit mit <span><span>den Eltern<\/span><\/span><\/h2>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Wir legen gro\u00dfen Wert auf eine enge Zusammenarbeit zwischen Eltern und Lehrkr\u00e4ften, um die optimale Entwicklung eines jeden Kindes zu gew\u00e4hrleisten. Im Mittelpunkt unserer p\u00e4dagogischen Philosophie steht das Kind, aber wir sind uns bewusst, dass die Eltern die besten Experten f\u00fcr ihre Kinder sind.\u00a0<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-746d48d e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"746d48d\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-034437b e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"034437b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-39233c9 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"39233c9\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-29e90ef ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"29e90ef\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text-left icon-lef-right-aligin elementor-animation- media\">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  text-center\">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon fas fa-child\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    T\u00e4gliche Gespr\u00e4che                <\/h3>\n                        \t\t  <p>T\u00e4gliche Gespr\u00e4che beim Bringen und Abholen des Kindes, bei denen wichtige Neuigkeiten oder Probleme besprochen werden k\u00f6nnen. Die P\u00e4dagoginnen und P\u00e4dagogen nehmen sich Zeit, um auf die Fragen und Sorgen der Eltern einzugehen.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b37a3b2 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"b37a3b2\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text-left icon-lef-right-aligin elementor-animation- media\">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  text-center\">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon fas fa-volleyball-ball\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Aktivit\u00e4ten &amp; Events                <\/h3>\n                        \t\t  <p>Klassenaktivit\u00e4ten, Veranstaltungen oder Auff\u00fchrungen, bei denen die Eltern zur Teilnahme ermutigt werden. Dadurch erhalten die Eltern einen Einblick in die Kindergartenerfahrungen ihres Kindes.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aeb2e05 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"aeb2e05\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text-left icon-lef-right-aligin elementor-animation- media\">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  text-center\">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon fas fa-users\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Elterngespr\u00e4che                <\/h3>\n                        \t\t  <p>Regelm\u00e4\u00dfig stattfindende individuelle Eltern-Lehrer-Gespr\u00e4che, in denen ausf\u00fchrliche Diskussionen \u00fcber das Lernen, die Entwicklung, das Verhalten usw. des Kindes unter vier Augen gef\u00fchrt werden k\u00f6nnen. Bei diesen Treffen werden auch die Fortschrittsberichte besprochen.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8321d0d ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"8321d0d\" data-element_type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text-left icon-lef-right-aligin elementor-animation- media\">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  text-center\">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon fas fa-newspaper\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Mitteilungen &amp; Neuigkeiten                <\/h3>\n                        \t\t  <p>Mitteilungen, Rundbriefe und andere schriftliche Informationen, um die Eltern \u00fcber Klassenaktivit\u00e4ten, Unterrichtspl\u00e4ne, organisatorische Informationen usw. zu informieren.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4329ff7 elementor-widget elementor-widget-spacer\" data-id=\"4329ff7\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cfba9de e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"cfba9de\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19397ae elementor-widget elementor-widget-image\" data-id=\"19397ae\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"770\" height=\"514\" src=\"https:\/\/dbsaa.de\/wp-content\/uploads\/2024\/02\/IMG_8893-1024x683.jpg\" class=\"attachment-large size-large wp-image-6434\" alt=\"\" srcset=\"https:\/\/dbsaa.de\/wp-content\/uploads\/2024\/02\/IMG_8893-1024x683.jpg 1024w, https:\/\/dbsaa.de\/wp-content\/uploads\/2024\/02\/IMG_8893-300x200.jpg 300w, https:\/\/dbsaa.de\/wp-content\/uploads\/2024\/02\/IMG_8893-768x512.jpg 768w, https:\/\/dbsaa.de\/wp-content\/uploads\/2024\/02\/IMG_8893-1536x1024.jpg 1536w, https:\/\/dbsaa.de\/wp-content\/uploads\/2024\/02\/IMG_8893-2048x1365.jpg 2048w, https:\/\/dbsaa.de\/wp-content\/uploads\/2024\/02\/IMG_8893-18x12.jpg 18w, https:\/\/dbsaa.de\/wp-content\/uploads\/2024\/02\/IMG_8893-600x400.jpg 600w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4d5acc7 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"4d5acc7\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-35ad3ba e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"35ad3ba\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-900c07c e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"900c07c\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4400a73 elementor-widget elementor-widget-elementskit-heading\" data-id=\"4400a73\" data-element_type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title\">Kindergartenleitung<\/h2><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7a8dab5 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"7a8dab5\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8f26883 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"8f26883\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e8822d1 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"e8822d1\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1bd1680 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"1bd1680\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48734d9 elementor-widget elementor-widget-ha-member happy-addon ha-member\" data-id=\"48734d9\" data-element_type=\"widget\" data-widget_type=\"ha-member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t\t\t<figure class=\"ha-member-figure\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"708\" height=\"1024\" src=\"https:\/\/dbsaa.de\/wp-content\/uploads\/2023\/11\/Kleo-2-708x1024.jpg\" class=\"elementor-animation-disable-animation attachment-large size-large wp-image-5805\" alt=\"\" srcset=\"https:\/\/dbsaa.de\/wp-content\/uploads\/2023\/11\/Kleo-2-708x1024.jpg 708w, https:\/\/dbsaa.de\/wp-content\/uploads\/2023\/11\/Kleo-2-207x300.jpg 207w, https:\/\/dbsaa.de\/wp-content\/uploads\/2023\/11\/Kleo-2-768x1111.jpg 768w, https:\/\/dbsaa.de\/wp-content\/uploads\/2023\/11\/Kleo-2-1062x1536.jpg 1062w, https:\/\/dbsaa.de\/wp-content\/uploads\/2023\/11\/Kleo-2-1416x2048.jpg 1416w, https:\/\/dbsaa.de\/wp-content\/uploads\/2023\/11\/Kleo-2-8x12.jpg 8w, https:\/\/dbsaa.de\/wp-content\/uploads\/2023\/11\/Kleo-2-600x868.jpg 600w, https:\/\/dbsaa.de\/wp-content\/uploads\/2023\/11\/Kleo-2-scaled.jpg 1770w\" sizes=\"(max-width: 708px) 100vw, 708px\" \/>\t\t\t<\/figure>\n\t\t\n\t\t<div class=\"ha-member-body\">\n\t\t\t<h2 class=\"ha-member-name\">Kleonike Chrissochou\u200b<\/h2>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"ha-member-bio\">\n\t\t\t\t\t<p>kindergarten@dbsaa.de<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4b82085 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"4b82085\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Kindergarten Our kindergarten has an enrollment of around 105 children between the ages of 1-6 years. The children are organized into groups of 16-20 students led by German-speaking educators and Ethiopian teaching assistants. Pedagogical Approach Our pedagogical approach focuses on each child&#8217;s developmental needs, experiences and interests. We aim to encourage independence, empathy, frustration tolerance and hands-on learning through play and exploration. Our goals are to facilitate well-rounded development across physical, cognitive, language, social-emotional and other domains. Image of the Child We see each child as special and unique with their own strengths, talents, interests, needs and learning styles. Our role is to nurture and empower each child&#8217;s individuality and self-confidence. We aim to support their positive self-image and help them build on their abilities and potential as individuals. Facilities and Daily Routines Our facility has several rooms including a large nursery room, three kindergarten group rooms, two preschool rooms, an outdoor area and more. The daily schedule provides structure and routine. It includes time for play, learning activities, meals, rest and targeted language instruction. Highlights of the schedule: Morning Schedule 7:30 am &#8211; Arrival of the children 8:15 am &#8211; Breakfast 8:45 am &#8211; Morning circle 9:15 am &#8211; Open group work Language support, early musical education, cooking and baking, sports. 10:45 am &#8211; Fruit snack 11:00 am &#8211; Free play and outdoor activities 12:00 pm &#8211; Lunch 01:00 pm &#8211; Nap\/rest time Afternoon Schedule 02:00 pm &#8211; Afternoon snacks 02:15 pm &#8211; Language support and implementation of joint project work on current topics (Christmas, Easter, Meskel etc.) 03:00 pm &#8211; Free play\/sports in the garden 04:00 pm &#8211; Pick up time Programs and Activities Our educational concepts align with the Thuringian Curriculum, focusing on child development areas like language, math, music, art, science, motor skills and socio-cultural education. We have the KonLab language program, a research-based early language development program beneficial for children with needs. Children receive 1-2 hours daily of KonLab instruction. Daily activities provide a balanced mix of structure and free play. Circle time, creative lessons, music and role playing are included. Sports and motor activities facilitate coordination. Free play is also essential for children to explore interests, with teacher support. A blend of guided and open exploration caters to different learning styles. Nursery Group Our nursery provides specialized care and education for infants and young toddlers. With a lower teacher-student ratio, we can provide individualized attention for our littlest learners. The nursery focuses on sensory learning, motor skills, communicating needs, and socialization. This multi-age grouping allows children to learn collaboratively while being taught at their own developmental level. Mice Kindergarten School The kindergarten groups contain 16-20 children each. Students remain with the same group peers and teachers for consistency. Groups are named after animals to make them more fun and engaging for the children. Zebras Elephants Camel Preschool Groups The preschool groups help transition children into primary school learning. The curriculum focuses more on early math, literacy, and social-emotional skills to prepare them for Grade 1. Leopards Giraffes Working with Parents We place immense importance on building close cooperation between parents and educators for each child&#8217;s optimal development. Our teaching philosophy centers around the child, but we recognize parents are the foremost experts on their children.\u00a0 Daily Check-ins Daily check-ins at drop-off and pick up where important updates or issues can be discussed. Teachers take time to address parental questions or concerns. Activities &amp; Events Class activities, events, or performances that parents are encouraged to attend and participate in. This gives parents visibility into their child&#8217;s kindergarten experiences. Parent Teacher Meeting Individual parent-teacher meetings that occur periodically where in-depth discussions about the child&#8217;s learning, growth, behaviors, etc. can take place privately. Meetings include reviewing progress reports. News &amp; Updates Notices, newsletters, and other written updates to inform parents on class activities, lesson plans, organizational information, etc. Kindergarten Management Kleonike Chrissochou\u200b kindergarten@dbsaa.de<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_piecal_is_event":false,"_piecal_start_date":"","_piecal_end_date":"","_piecal_is_allday":false,"footnotes":""},"_links":{"self":[{"href":"https:\/\/dbsaa.de\/de\/wp-json\/wp\/v2\/pages\/613"}],"collection":[{"href":"https:\/\/dbsaa.de\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dbsaa.de\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dbsaa.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dbsaa.de\/de\/wp-json\/wp\/v2\/comments?post=613"}],"version-history":[{"count":10,"href":"https:\/\/dbsaa.de\/de\/wp-json\/wp\/v2\/pages\/613\/revisions"}],"predecessor-version":[{"id":10095,"href":"https:\/\/dbsaa.de\/de\/wp-json\/wp\/v2\/pages\/613\/revisions\/10095"}],"wp:attachment":[{"href":"https:\/\/dbsaa.de\/de\/wp-json\/wp\/v2\/media?parent=613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}